{"id":3525,"date":"2025-07-29T12:44:53","date_gmt":"2025-07-29T10:44:53","guid":{"rendered":"https:\/\/lignamo.com\/eventi-della-settimana-a-lignano-sabbiadoro-28-luglio-3-agosto-2025\/"},"modified":"2025-07-29T12:48:55","modified_gmt":"2025-07-29T10:48:55","slug":"eventi-della-settimana-a-lignano-sabbiadoro-28-luglio-3-agosto-2025","status":"publish","type":"post","link":"https:\/\/lignamo.com\/it\/eventi-della-settimana-a-lignano-sabbiadoro-28-luglio-3-agosto-2025\/","title":{"rendered":"Eventi della settimana a Lignano Sabbiadoro (28 luglio \u2013 3 agosto 2025)"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"3525\" class=\"elementor elementor-3525 elementor-3513\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-74a4584 e-flex e-con-boxed e-con e-parent\" data-id=\"74a4584\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5d7cb21 elementor-widget elementor-widget-text-editor\" data-id=\"5d7cb21\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tScopri cosa ti aspetta questa settimana a Lignano: musica, spettacoli, incontri culturali e divertimento per tutti. Ecco gli appuntamenti imperdibili da segnare in agenda!<br><br>&nbsp;<br><h2><strong>\ud83c\udf1f<\/strong><strong> Estate in Piazza Ursella | spettacoli per tutti \u2013 Sabbiadoro<\/strong><\/h2><br><strong>Ogni sera alle 21:00 in Piazza Ursella<\/strong> (via Latisana): musica dal vivo, animazione e <em>Fun &amp; Baby Dance<\/em> per bambini e famiglie.<br><strong>Programma prossime settimane:<\/strong><br><ul>\r\n \t<li>Mercoled\u00ec 30 luglio: <em>\u201cLignano per\u2026 la musica\u201d<\/em>, Fabio Steve Ulliana &amp; Off Limits Band<\/li>\r\n \t<li>Luned\u00ec 4 agosto: <em>Fun &amp; Baby Dance<\/em><\/li>\r\n \t<li>Venerd\u00ec 8 agosto: <em>Fun &amp; Baby Dance<\/em><\/li>\r\n \t<li>Luned\u00ec 11 agosto: <em>Fun &amp; Baby Dance<\/em>\r\nIngresso libero e atmosfera estiva da vivere insieme.<\/li>\r\n<\/ul><br>&nbsp;<br><h2><strong>\ud83c\udfa4<\/strong><strong> Lignano Summer Live Festival \u2013 Sabbiadoro &amp; Pineta<\/strong><\/h2><br>Il Festival continua tra Beach Arena (<em>Ufficio Spiaggia\u202f5<\/em>) e <strong>Piazza Marcello D\u2019Olivo<\/strong> a Pineta.<br><strong>Evento in evidenza questa settimana:<\/strong><br><ul>\r\n \t<li>Gioved\u00ec 31 luglio alle ore 20:00: <strong>Extreme live<\/strong> all\u2019<strong>Arena Alpe Adria<\/strong>. La storica band hard rock americana arriva a Lignano per il <em>Lignano Sunset Festival<\/em>. Biglietti disponibili su TicketOne e Vivaticket.<\/li>\r\n<\/ul><br>&nbsp;<br><h2><strong>\ud83d\udcda<\/strong><strong> Incontri con l\u2019Autore | letteratura live \u2013 Pineta<\/strong><\/h2><br><strong>Gioved\u00ec 31 luglio alle 18:30 al Palapineta (Parco del Mare)<\/strong>. Presentazioni di libri con autori locali e nazionali, una serata culturale perfetta per gli appassionati di storie e parole. Interverr\u00e0 Giordano Bruno Guerri, \u201cStoria del mondo. Dal Big Bang a oggi\u201d.<br><br>&nbsp;<br><h2><strong>\ud83c\udf77<\/strong><strong> I Gusti di Casa Nostra | enogastronomia al Parco Hemingway \u2013 Pineta<\/strong><\/h2><br>Segna in agenda: gioved\u00ec 7 e gioved\u00ec 21 agosto, dalle 8.00 alle 13.00, una full\u2011immersion nei sapori del Friuli\u202fVenezia\u202fGiulia: cibo, esperienze e tradizioni del territorio. Imperdibile per gli amanti del buon cibo locale.<br><br>&nbsp;<br><h2><strong>\ud83d\udcdd<\/strong><strong> Suggerimenti di LignAmo<\/strong><\/h2><br><ul>\r\n \t<li><strong>Appuntamenti serali in piazza:<\/strong> perfetti per famiglie e giovani, gratuiti e in piena atmosfera estiva.<\/li>\r\n \t<li><strong>Food&amp;Drink:<\/strong> dopo uno spettacolo c&#8217;\u00e8 solo l&#8217;imbarazzo della scelta tra locali per l\u2019aperitivo o una cena last-minute.<\/li>\r\n \t<li><strong>Cultura e natura:<\/strong> continua a seguire <em>Incontri con l\u2019Autore<\/em> e immergiti nei sapori nel weekend con <em>I Gusti di Casa Nostra.<\/em><\/li>\r\n<\/ul><br>\ud83d\udcf8 <strong>Hai partecipato a uno di questi momenti?<\/strong> Condividi la tua foto su Instagram taggando <span style=\"color: #9f5fff;\"><strong data-start=\"2574\" data-end=\"2587\">@lign_amo<\/strong><\/span>\u00a0e usa <span style=\"color: #ff4f9c;\"><strong>#lign_amo<\/strong><\/span>: potresti finire nel nostro feed!\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Scopri cosa ti aspetta questa settimana a Lignano: musica, spettacoli, incontri culturali e divertimento per tutti. Ecco gli appuntamenti imperdibili da segnare in agenda! &nbsp; \ud83c\udf1f Estate in Piazza Ursella | spettacoli per tutti \u2013 Sabbiadoro Ogni sera alle 21:00 in Piazza Ursella (via Latisana): musica dal vivo, animazione e Fun &amp; Baby Dance per [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3523,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[45],"tags":[],"class_list":["post-3525","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-categorizzato"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Eventi della settimana a Lignano Sabbiadoro (28 luglio \u2013 3 agosto 2025) - LignAmo | Share your vibes<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lignamo.com\/events-of-the-week-in-lignano-sabbiadoro-july-28-august-3-2025\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Eventi della settimana a Lignano Sabbiadoro (28 luglio \u2013 3 agosto 2025) - LignAmo | Share your vibes\" \/>\n<meta property=\"og:description\" content=\"Scopri cosa ti aspetta questa settimana a Lignano: musica, spettacoli, incontri culturali e divertimento per tutti. Ecco gli appuntamenti imperdibili da segnare in agenda! &nbsp; \ud83c\udf1f Estate in Piazza Ursella | spettacoli per tutti \u2013 Sabbiadoro Ogni sera alle 21:00 in Piazza Ursella (via Latisana): musica dal vivo, animazione e Fun &amp; Baby Dance per [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lignamo.com\/events-of-the-week-in-lignano-sabbiadoro-july-28-august-3-2025\/\" \/>\n<meta property=\"og:site_name\" content=\"LignAmo | Share your vibes\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/lignamo\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-29T10:44:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-29T10:48:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lignamo.com\/wp-content\/uploads\/2025\/07\/15-events-july-august-lignamo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin-adigi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin-adigi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lignamo.com\\\/events-of-the-week-in-lignano-sabbiadoro-july-28-august-3-2025\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lignamo.com\\\/events-of-the-week-in-lignano-sabbiadoro-july-28-august-3-2025\\\/\"},\"author\":{\"name\":\"admin-adigi\",\"@id\":\"https:\\\/\\\/lignamo.com\\\/#\\\/schema\\\/person\\\/8c5b9a91bef0c9f421cf0b39f3669aac\"},\"headline\":\"Eventi della settimana a Lignano Sabbiadoro (28 luglio \u2013 3 agosto 2025)\",\"datePublished\":\"2025-07-29T10:44:53+00:00\",\"dateModified\":\"2025-07-29T10:48:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lignamo.com\\\/events-of-the-week-in-lignano-sabbiadoro-july-28-august-3-2025\\\/\"},\"wordCount\":339,\"publisher\":{\"@id\":\"https:\\\/\\\/lignamo.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/lignamo.com\\\/events-of-the-week-in-lignano-sabbiadoro-july-28-august-3-2025\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lignamo.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/15-events-july-august-lignamo.jpg\",\"articleSection\":[\"Non categorizzato\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lignamo.com\\\/events-of-the-week-in-lignano-sabbiadoro-july-28-august-3-2025\\\/\",\"url\":\"https:\\\/\\\/lignamo.com\\\/events-of-the-week-in-lignano-sabbiadoro-july-28-august-3-2025\\\/\",\"name\":\"Eventi della settimana a Lignano Sabbiadoro (28 luglio \u2013 3 agosto 2025) - LignAmo | Share your vibes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lignamo.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lignamo.com\\\/events-of-the-week-in-lignano-sabbiadoro-july-28-august-3-2025\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lignamo.com\\\/events-of-the-week-in-lignano-sabbiadoro-july-28-august-3-2025\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lignamo.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/15-events-july-august-lignamo.jpg\",\"datePublished\":\"2025-07-29T10:44:53+00:00\",\"dateModified\":\"2025-07-29T10:48:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lignamo.com\\\/events-of-the-week-in-lignano-sabbiadoro-july-28-august-3-2025\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lignamo.com\\\/events-of-the-week-in-lignano-sabbiadoro-july-28-august-3-2025\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/lignamo.com\\\/events-of-the-week-in-lignano-sabbiadoro-july-28-august-3-2025\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lignamo.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/15-events-july-august-lignamo.jpg\",\"contentUrl\":\"https:\\\/\\\/lignamo.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/15-events-july-august-lignamo.jpg\",\"width\":1200,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lignamo.com\\\/events-of-the-week-in-lignano-sabbiadoro-july-28-august-3-2025\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/lignamo.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Eventi della settimana a Lignano Sabbiadoro (28 luglio \u2013 3 agosto 2025)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lignamo.com\\\/#website\",\"url\":\"https:\\\/\\\/lignamo.com\\\/\",\"name\":\"LignAmo | Share your vibes\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/lignamo.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lignamo.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lignamo.com\\\/#organization\",\"name\":\"LignAmo | Share your vibes\",\"url\":\"https:\\\/\\\/lignamo.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/lignamo.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lignamo.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/logo-lign_amo_23-07-2025.png\",\"contentUrl\":\"https:\\\/\\\/lignamo.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/logo-lign_amo_23-07-2025.png\",\"width\":600,\"height\":300,\"caption\":\"LignAmo | Share your vibes\"},\"image\":{\"@id\":\"https:\\\/\\\/lignamo.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/lignamo\",\"https:\\\/\\\/www.instagram.com\\\/lign_amo\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lignamo.com\\\/#\\\/schema\\\/person\\\/8c5b9a91bef0c9f421cf0b39f3669aac\",\"name\":\"admin-adigi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/96ce9a00fcf195a61c165fc41ac931eaacb7d76013f3a22f1a426928e463fd20?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/96ce9a00fcf195a61c165fc41ac931eaacb7d76013f3a22f1a426928e463fd20?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/96ce9a00fcf195a61c165fc41ac931eaacb7d76013f3a22f1a426928e463fd20?s=96&d=mm&r=g\",\"caption\":\"admin-adigi\"},\"sameAs\":[\"https:\\\/\\\/lignamo.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Eventi della settimana a Lignano Sabbiadoro (28 luglio \u2013 3 agosto 2025) - LignAmo | Share your vibes","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lignamo.com\/events-of-the-week-in-lignano-sabbiadoro-july-28-august-3-2025\/","og_locale":"it_IT","og_type":"article","og_title":"Eventi della settimana a Lignano Sabbiadoro (28 luglio \u2013 3 agosto 2025) - LignAmo | Share your vibes","og_description":"Scopri cosa ti aspetta questa settimana a Lignano: musica, spettacoli, incontri culturali e divertimento per tutti. Ecco gli appuntamenti imperdibili da segnare in agenda! &nbsp; \ud83c\udf1f Estate in Piazza Ursella | spettacoli per tutti \u2013 Sabbiadoro Ogni sera alle 21:00 in Piazza Ursella (via Latisana): musica dal vivo, animazione e Fun &amp; Baby Dance per [&hellip;]","og_url":"https:\/\/lignamo.com\/events-of-the-week-in-lignano-sabbiadoro-july-28-august-3-2025\/","og_site_name":"LignAmo | Share your vibes","article_publisher":"https:\/\/www.facebook.com\/lignamo","article_published_time":"2025-07-29T10:44:53+00:00","article_modified_time":"2025-07-29T10:48:55+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/lignamo.com\/wp-content\/uploads\/2025\/07\/15-events-july-august-lignamo.jpg","type":"image\/jpeg"}],"author":"admin-adigi","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"admin-adigi","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lignamo.com\/events-of-the-week-in-lignano-sabbiadoro-july-28-august-3-2025\/#article","isPartOf":{"@id":"https:\/\/lignamo.com\/events-of-the-week-in-lignano-sabbiadoro-july-28-august-3-2025\/"},"author":{"name":"admin-adigi","@id":"https:\/\/lignamo.com\/#\/schema\/person\/8c5b9a91bef0c9f421cf0b39f3669aac"},"headline":"Eventi della settimana a Lignano Sabbiadoro (28 luglio \u2013 3 agosto 2025)","datePublished":"2025-07-29T10:44:53+00:00","dateModified":"2025-07-29T10:48:55+00:00","mainEntityOfPage":{"@id":"https:\/\/lignamo.com\/events-of-the-week-in-lignano-sabbiadoro-july-28-august-3-2025\/"},"wordCount":339,"publisher":{"@id":"https:\/\/lignamo.com\/#organization"},"image":{"@id":"https:\/\/lignamo.com\/events-of-the-week-in-lignano-sabbiadoro-july-28-august-3-2025\/#primaryimage"},"thumbnailUrl":"https:\/\/lignamo.com\/wp-content\/uploads\/2025\/07\/15-events-july-august-lignamo.jpg","articleSection":["Non categorizzato"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/lignamo.com\/events-of-the-week-in-lignano-sabbiadoro-july-28-august-3-2025\/","url":"https:\/\/lignamo.com\/events-of-the-week-in-lignano-sabbiadoro-july-28-august-3-2025\/","name":"Eventi della settimana a Lignano Sabbiadoro (28 luglio \u2013 3 agosto 2025) - LignAmo | Share your vibes","isPartOf":{"@id":"https:\/\/lignamo.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lignamo.com\/events-of-the-week-in-lignano-sabbiadoro-july-28-august-3-2025\/#primaryimage"},"image":{"@id":"https:\/\/lignamo.com\/events-of-the-week-in-lignano-sabbiadoro-july-28-august-3-2025\/#primaryimage"},"thumbnailUrl":"https:\/\/lignamo.com\/wp-content\/uploads\/2025\/07\/15-events-july-august-lignamo.jpg","datePublished":"2025-07-29T10:44:53+00:00","dateModified":"2025-07-29T10:48:55+00:00","breadcrumb":{"@id":"https:\/\/lignamo.com\/events-of-the-week-in-lignano-sabbiadoro-july-28-august-3-2025\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lignamo.com\/events-of-the-week-in-lignano-sabbiadoro-july-28-august-3-2025\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/lignamo.com\/events-of-the-week-in-lignano-sabbiadoro-july-28-august-3-2025\/#primaryimage","url":"https:\/\/lignamo.com\/wp-content\/uploads\/2025\/07\/15-events-july-august-lignamo.jpg","contentUrl":"https:\/\/lignamo.com\/wp-content\/uploads\/2025\/07\/15-events-july-august-lignamo.jpg","width":1200,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/lignamo.com\/events-of-the-week-in-lignano-sabbiadoro-july-28-august-3-2025\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/lignamo.com\/"},{"@type":"ListItem","position":2,"name":"Eventi della settimana a Lignano Sabbiadoro (28 luglio \u2013 3 agosto 2025)"}]},{"@type":"WebSite","@id":"https:\/\/lignamo.com\/#website","url":"https:\/\/lignamo.com\/","name":"LignAmo | Share your vibes","description":"","publisher":{"@id":"https:\/\/lignamo.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lignamo.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/lignamo.com\/#organization","name":"LignAmo | Share your vibes","url":"https:\/\/lignamo.com\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/lignamo.com\/#\/schema\/logo\/image\/","url":"https:\/\/lignamo.com\/wp-content\/uploads\/2025\/07\/logo-lign_amo_23-07-2025.png","contentUrl":"https:\/\/lignamo.com\/wp-content\/uploads\/2025\/07\/logo-lign_amo_23-07-2025.png","width":600,"height":300,"caption":"LignAmo | Share your vibes"},"image":{"@id":"https:\/\/lignamo.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/lignamo","https:\/\/www.instagram.com\/lign_amo\/"]},{"@type":"Person","@id":"https:\/\/lignamo.com\/#\/schema\/person\/8c5b9a91bef0c9f421cf0b39f3669aac","name":"admin-adigi","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/96ce9a00fcf195a61c165fc41ac931eaacb7d76013f3a22f1a426928e463fd20?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/96ce9a00fcf195a61c165fc41ac931eaacb7d76013f3a22f1a426928e463fd20?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/96ce9a00fcf195a61c165fc41ac931eaacb7d76013f3a22f1a426928e463fd20?s=96&d=mm&r=g","caption":"admin-adigi"},"sameAs":["https:\/\/lignamo.com"]}]}},"_links":{"self":[{"href":"https:\/\/lignamo.com\/it\/wp-json\/wp\/v2\/posts\/3525","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lignamo.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lignamo.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lignamo.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lignamo.com\/it\/wp-json\/wp\/v2\/comments?post=3525"}],"version-history":[{"count":1,"href":"https:\/\/lignamo.com\/it\/wp-json\/wp\/v2\/posts\/3525\/revisions"}],"predecessor-version":[{"id":3526,"href":"https:\/\/lignamo.com\/it\/wp-json\/wp\/v2\/posts\/3525\/revisions\/3526"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lignamo.com\/it\/wp-json\/wp\/v2\/media\/3523"}],"wp:attachment":[{"href":"https:\/\/lignamo.com\/it\/wp-json\/wp\/v2\/media?parent=3525"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lignamo.com\/it\/wp-json\/wp\/v2\/categories?post=3525"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lignamo.com\/it\/wp-json\/wp\/v2\/tags?post=3525"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}